{"id":10687,"date":"2018-01-11T13:11:32","date_gmt":"2018-01-11T12:11:32","guid":{"rendered":"https:\/\/save-society.org\/home\/?page_id=10687"},"modified":"2020-11-26T10:49:09","modified_gmt":"2020-11-26T09:49:09","slug":"geschenke","status":"publish","type":"page","link":"https:\/\/save-society.org\/home\/geschenke\/","title":{"rendered":"Geschenke"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Service Section&#8220; _builder_version=&#8220;3.22&#8243; background_image=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/06\/savesociety-fotos-4-1-1.jpg&#8220; parallax=&#8220;on&#8220; parallax_method=&#8220;off&#8220; background_video_width=&#8220;1920&#8243; background_video_height=&#8220;1200&#8243; allow_player_pause=&#8220;on&#8220; custom_margin=&#8220;0px|0px|0px|0px&#8220; custom_padding=&#8220;0px|0px|0px|0px&#8220;][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;|5%|0px|5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Geschenke&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; header_text_align=&#8220;justify&#8220; header_text_color=&#8220;#ffffff&#8220; text_orientation=&#8220;justified&#8220; background_layout=&#8220;dark&#8220; custom_padding=&#8220;5%|5%||5%&#8220;]<\/p>\n<h1>Geschenke<\/h1>\n<p><\/p>\n<p>Wer Menschen helfen m\u00f6chte, findet zahlreiche M\u00f6glichkeiten auf unserer Webseite. Wer eine besondere Geschenkidee sucht, findet hier verschiedene kreative Ideen. Wir haben Motive gestaltet, die einen aufkl\u00e4renden Charakter besitzen. Diese werden auf verschiedene Produkte gedruckt. Ein Hoodie, Mousepads oder ein Stoffbeutel kann die Welt nicht sonderlich besser machen. M\u00f6chte man jedoch ein Zeichen setzen und sein &#8222;Statement&#8220; anderen Menschen mitteilen, dann sind unsere Designs und Produkte eine gute M\u00f6glichkeit. Wir m\u00f6chten durch unsere Motivkollektionen und Designs eine M\u00f6glichkeit bieten, eine Meinung gegen Ausgrenzung und f\u00fcr Toleranz zu transportieren. Menschen sollten nicht als Spielball behandelt werden. Suchen Sie ein Geschenk f\u00fcr Frauen, M\u00e4nner, Kinder oder Babys? Kreative Geschenkideen warten auf eine Erkundung.<\/p>\n<p>Unterst\u00fctzen Sie unsere Arbeit gegen Diskriminierung, Mobbing und Altersarmut. F\u00fchlen Sie sich manchmal nur als Mittel zum Zweck? Dann schauen Sie sich unser Motiv: <a title=\"Auf meine Kosten\" href=\"https:\/\/save-society.org\/home\/auf-meine-kosten\/\">Auf meine Kosten<\/a> an oder ben\u00f6tigen Sie ein neues <a title=\"Mousepad\" href=\"https:\/\/save-society.org\/home\/mousepad\/\">Mousepad<\/a>&nbsp;und&nbsp;<a title=\"Tassen\" href=\"https:\/\/save-society.org\/home\/tassen\/\">Tassen<\/a>&nbsp;oder ein neues&nbsp;<a title=\"T-Shirt\" href=\"https:\/\/save-society.org\/home\/t-shirt\/\">T-Shirt<\/a>, <a title=\"Cap\" href=\"https:\/\/save-society.org\/home\/cap-muetze\/\">Cap\/M\u00fctze<\/a>&nbsp;oder ein&nbsp;<a title=\"Kissen\" href=\"https:\/\/save-society.org\/home\/kissenbezuege\/\">Kissen<\/a> oder interessieren Sie sich f\u00fcr einen unserer &#8222;<a title=\"Stoffbeutel\" href=\"https:\/\/save-society.org\/home\/stoffbeutel\/\">Stoffbeutel<\/a>&#8220; oder m\u00f6chten Sie etwas anderes <a title=\"Einkaufen\" href=\"https:\/\/save-society.org\/home\/einkaufen-und-die-save-society-unterstuetzen\/\">Einkaufen<\/a>? Hier finden Sie alle <a title=\"Produkte\" href=\"https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/all\" target=\"_blank\" rel=\"noopener noreferrer\">Produkte<\/a> f\u00fcr&nbsp;<a title=\"Maenner\" href=\"https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/m%C3%A4nner?q=D1\" target=\"_blank\" rel=\"noopener noreferrer\">M\u00e4nner<\/a>, <a title=\"Frauen\" href=\"https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/frauen?q=D3\" target=\"_blank\" rel=\"noopener noreferrer\">Frauen<\/a>&nbsp;und&nbsp;<a title=\"Kinder Babays\" href=\"https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/kinder+%26+babys?q=D4\" target=\"_blank\" rel=\"noopener noreferrer\">Kinder &amp; Babys<\/a>, oder suchen Sie nach&nbsp;<a title=\"Accessoires\" href=\"https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/accessoires?q=D5\" target=\"_blank\" rel=\"noopener noreferrer\">Accessoires<\/a> oder einer&nbsp;<a title=\"Huellen\" href=\"https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/h%C3%BCllen?q=D19\" target=\"_blank\" rel=\"noopener noreferrer\">H\u00fcllen<\/a>&nbsp;f\u00fcr Ihr Handy oder Tablet?<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;|5%||5%&#8220; custom_css_main_element=&#8220;z-index:9999;&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;MEN\u00dc SPREADSHIRT&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;1px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<p>\n<div id=\"mega-menu-wrap-max_mega_menu_4\" class=\"mega-menu-wrap\"><div class=\"mega-menu-toggle\"><div class=\"mega-toggle-blocks-left\"><div class='mega-toggle-block mega-menu-toggle-animated-block mega-toggle-block-1' id='mega-toggle-block-1'><button aria-controls=\"mega-menu-max_mega_menu_4\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-label=\"Toggle Menu\" class=\"mega-toggle-animated mega-toggle-animated-slider\" type=\"button\">\n                  <span class=\"mega-toggle-animated-box\">\n                    <span class=\"mega-toggle-animated-inner\"><\/span>\n                  <\/span>\n                <\/button><\/div><\/div><div class=\"mega-toggle-blocks-center\"><\/div><div class=\"mega-toggle-blocks-right\"><\/div><\/div><ul id=\"mega-menu-max_mega_menu_4\" class=\"mega-menu max-mega-menu mega-menu-horizontal mega-no-js\" data-event=\"click\" data-effect=\"slide\" data-effect-speed=\"200\" data-effect-mobile=\"slide\" data-effect-speed-mobile=\"200\" data-mobile-force-width=\"false\" data-second-click=\"go\" data-document-click=\"collapse\" data-vertical-behaviour=\"standard\" data-breakpoint=\"1000\" data-unbind=\"true\" data-mobile-state=\"collapse_all\" data-mobile-direction=\"vertical\"><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10449\" id=\"mega-menu-item-10449\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/all\">ALLE PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10450\" id=\"mega-menu-item-10450\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner?q=D1\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10450\">M\u00c4NNER<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10450'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10451\" id=\"mega-menu-item-10451\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner?q=D1\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10452\" id=\"mega-menu-item-10452\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+t-shirts?q=P24\">T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10453\" id=\"mega-menu-item-10453\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+langarmshirts?q=P25\">LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10454\" id=\"mega-menu-item-10454\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+pullover+%26+hoodies?q=P27\">PULLOVER & HOODIES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10455\" id=\"mega-menu-item-10455\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+jacken+%26+westen?q=P28\">JACKEN & WESTEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10456\" id=\"mega-menu-item-10456\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+poloshirts?q=P26\">POLOSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10457\" id=\"mega-menu-item-10457\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+tank+tops?q=P101\">TANK TOPS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10458\" id=\"mega-menu-item-10458\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+bioprodukte?q=P68\">BIO PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10459\" id=\"mega-menu-item-10459\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+sportbekleidung?q=P92\">SPORT BEKLEIDUNG<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10460\" id=\"mega-menu-item-10460\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+arbeitskleidung?q=P97ciety.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/m%C3%A4nner+arbeitskleidung?q=P97\">ARBEITSKLEIDUNG<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10461\" id=\"mega-menu-item-10461\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen?q=D3\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10461\">FRAUEN<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10461'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10462\" id=\"mega-menu-item-10462\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen?q=D3\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10463\" id=\"mega-menu-item-10463\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+t-shirts?q=P33\">T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10464\" id=\"mega-menu-item-10464\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+langarmshirts?q=P35\">LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10465\" id=\"mega-menu-item-10465\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+pullover+%26+hoodies?q=P37\">PULLOVER & HOODIES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10466\" id=\"mega-menu-item-10466\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+jacken+%26+westen?q=P38\">JACKEN & WESTEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10467\" id=\"mega-menu-item-10467\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+poloshirts?q=P36\">POLOSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10468\" id=\"mega-menu-item-10468\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+tops?q=P34\">TOPS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10469\" id=\"mega-menu-item-10469\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+bioprodukte?q=P69\">BIO PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10470\" id=\"mega-menu-item-10470\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+sportbekleidung?q=P91\">SPORT BEKLEIDUNG<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10471\" id=\"mega-menu-item-10471\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+arbeitskleidung?q=P98\">ARBEITSKLEIDUNG<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10472\" id=\"mega-menu-item-10472\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys?q=D4\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10472\">KINDER & BABYS<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10472'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10473\" id=\"mega-menu-item-10473\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys?q=D4\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10474\" id=\"mega-menu-item-10474\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+t-shirts?q=P40\">T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10475\" id=\"mega-menu-item-10475\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+langarmshirts?q=P93\">LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10476\" id=\"mega-menu-item-10476\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+pullover+%26+hoodies?q=P41\">PULLOVER & HOODIES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10477\" id=\"mega-menu-item-10477\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+t-shirts?q=P42\">BABY T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10478\" id=\"mega-menu-item-10478\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+langarmshirts?q=P94\">BABY LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10479\" id=\"mega-menu-item-10479\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+bodys?q=P43\">BABY BODYS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10480\" id=\"mega-menu-item-10480\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+bioprodukte?q=P61\">BIO PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10481\" id=\"mega-menu-item-10481\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+accessoires?q=P77\">ACCESSOIRES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10482\" id=\"mega-menu-item-10482\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+l%C3%A4tzchen?q=P44\">BABY L\u00c4TZCHEN<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10483\" id=\"mega-menu-item-10483\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires?q=D5\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10483\">ACCESSOIRES<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10483'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10484\" id=\"mega-menu-item-10484\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires?q=D5\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10485\" id=\"mega-menu-item-10485\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+caps+%26+m%C3%BCtzen?q=P46\">CAPS & M\u00dcTZEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10486\" id=\"mega-menu-item-10486\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+sonstiges?q=P58\">HANDY & TABLET<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10487\" id=\"mega-menu-item-10487\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+taschen+%26+rucks%C3%A4cke?q=P47\">TASCHEN & RUCKS\u00c4CKE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10488\" id=\"mega-menu-item-10488\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+sch%C3%BCrzen?q=P48\">SCH\u00dcRZEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10489\" id=\"mega-menu-item-10489\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+kuscheltiere?q=P53\">KUSCHELTIERE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10490\" id=\"mega-menu-item-10490\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+tassen+%26+zubeh%C3%B6r?q=P49\">TASSEN & ZUBEH\u00d6R<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10491\" id=\"mega-menu-item-10491\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+kissen?q=P133\">KISSENBEZ\u00dcGE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10492\" id=\"mega-menu-item-10492\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+buttons+%26+anstecker?q=P50\">BUTTONS & ANSTECKER<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10493\" id=\"mega-menu-item-10493\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires?q=D5\">FEIERN & SCHENKEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10494\" id=\"mega-menu-item-10494\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+sonstiges?q=P58\">SONSTIGE<\/a><\/li><\/ul>\n<\/li><\/ul><\/div><br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Designs&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;1px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3>Designs<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; custom_css_main_element=&#8220;z-index:9;&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/07\/save-society-org_humangames_fashion.png&#8220; alt=&#8220;Human Games &#8211; Hoodie Motiv &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Hoodie Motiv &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/human-games\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/07\/save-society-org_mobbing.png&#8220; alt=&#8220;AAAAABA &#8211; Hoodie Design &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAABA &#8211; Hoodie Design &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/all&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/07\/save-society-org_toleranz.png&#8220; alt=&#8220;50\/50 &#8211; Poloshirt Motiv &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Poloshirt Motiv &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/all&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/07\/save-society-org_aufmeinekosten_fashion.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Poloshirt Motiv &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Poloshirt Motiv &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/auf-meine-kosten\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Stofftaschen&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_text_align=&#8220;left&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/stoffbeutel\/\" title=\"Stofftasche\">Stofftaschen<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10369&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-stoffbeutel.png&#8220; alt=&#8220;Human Games &#8211; Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/stoffbeutel\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-stoffbeutel.png&#8220; alt=&#8220;AAAAAABA &#8211; Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAAABA &#8211; Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/stoffbeutel\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/07\/teilen-stoffbeutel.png&#8220; alt=&#8220;50\/50 &#8211; Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/stoffbeutel\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-schultertasche-aus-recycling-material.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Designer Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Designer Tasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/stoffbeutel\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Hoodie&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/hoodie\/\" title=\"Hoodie\">Hoodie<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10373&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-hoodie-1.png&#8220; alt=&#8220;Human Games &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/hoodie\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;blau&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-frauen-premium-hoodie.png&#8220; alt=&#8220;AAAABA &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAABA &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/hoodie\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;pink&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-frauen-premium-hoodie.png&#8220; alt=&#8220;50\/50 &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/hoodie\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;rosa&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-maenner-premium-hoodie.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Hoodie &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/hoodie\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;lila&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Baby Kinderkleidung&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/baby-kinderkleidung\/\" title=\"Baby Kinderkleidung\">Baby Kinderkleidung<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10367&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-kinder-prem_002.png&#8220; alt=&#8220;Human Games &#8211; Baby Kinderkleidung &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Baby Kinderkleidung &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/baby-kinderkleidung\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;blau&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-baby-bio-laetzchen.png&#8220; alt=&#8220;AAAAABA &#8211; Baby Kinderkleidung &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAABA &#8211; Baby Kinderkleidung &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/baby-kinderkleidung\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;pink&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-baby-bio-laetzchen.png&#8220; alt=&#8220;50\/50 &#8211; Baby Kinderkleidung &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Baby Kinderkleidung &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/baby-kinderkleidung\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;rosa&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-baby-bio-kurzarm-kontrastbody-2.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Baby &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Baby &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/baby-kinderkleidung\/&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;lila&#8220; _builder_version=&#8220;4.7.4&#8243; hover_enabled=&#8220;0&#8243; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Jacken&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/jacke\/\" title=\"Jacken\">Jacken<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10368&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-hoodie-1.png&#8220; alt=&#8220;Human Games &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=1325&#038;appearance=763&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;blau&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-frauen-premium-kapuzenjacke.png&#8220; alt=&#8220;AAAAABA &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAABA &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=93&#038;appearance=648&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;pink&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-frauen-premium-hoodie.png&#8220; alt=&#8220;50\/50 &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=444&#038;appearance=4&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;rosa&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-maenner-premium-kapuzenjacke.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Jacke &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=93&#038;appearance=4&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;lila&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Rucksack&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/rucksack\/\" title=\"Rucksack\">Rucksack<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10370&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-sporttasche.png&#8220; alt=&#8220;Human Games &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=638&#038;appearance=2&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-turnbeutel.png&#8220; alt=&#8220;AAAABA &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAABA &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=1155&#038;appearance=2&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-turnbeutel.png&#8220; alt=&#8220;50\/50 &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=1155&#038;appearance=30&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-turnbeutel.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Rucksack &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=1155&#038;appearance=195&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Trinkflaschen&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/trinkflasche\/\" title=\"Trinkflaschen\">Trinkflaschen<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10372&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-trinkflasche.png&#8220; alt=&#8220;Human Games &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=757&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-trinkflasche.png&#8220; alt=&#8220;AAAAABA &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAABA &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=757&#038;appearance=37&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-trinkflasche.png&#8220; alt=&#8220;50\/50 &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=757&#038;appearance=37&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-trinkflasche.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Trinkflasche &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=757&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;T-Shirt&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/t-shirt\/\" title=\"T-Shirt\">T-Shirt<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10375&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-bio-t-sh.png&#8220; alt=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=461&#038;appearance=294&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-frauen-oversize-t-shirt.png&#8220; alt=&#8220;AAAAABA &#8211; T-Shirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAABA &#8211; T-Shirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=631&#038;appearance=231&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-frauen-premium-t-shirt.png&#8220; alt=&#8220;50\/50 &#8211; T-Shirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; T-Shirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=813&#038;appearance=39&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-maenner-polycotton-t-shirt.png&#8220; alt=&#8220;Auf meine Kosten &#8211; T-Shirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; T-Shirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=1202&#038;appearance=164&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Cap M\u00fctze&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/cap-muetze\/\" title=\"Cap\">Cap M\u00fctze<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10376&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-jersey-beanie.png&#8220; alt=&#8220;Human Games &#8211; Cap und Muetze &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Cap und Muetze &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/accessoires+caps+%26+m%C3%BCtzen?q=P46&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-snapback-cap.png&#8220; alt=&#8220;AAAAABA &#8211; Cap und Muetze &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAABA &#8211; Cap und Muetze &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/accessoires+caps+%26+m%C3%BCtzen?q=P46&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-snapback-cap.png&#8220; alt=&#8220;50\/50 &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/accessoires+caps+%26+m%C3%BCtzen?q=P46&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-snapback-cap-1.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Cap und Muetze &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Cap und Muetze &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/accessoires+caps+%26+m%C3%BCtzen?q=P46&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Poloshirt&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/poloshirt\/\" title=\"Poloshirt\">Poloshirt<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10378&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-polo-shi-1.png&#8220; alt=&#8220;Human Games &#8211; Poloshirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Poloshirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=1267&#038;appearance=1&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;blau&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-maenner-poloshirt.png&#8220; alt=&#8220;AAAAABA &#8211; Poloshirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAABA &#8211; Poloshirt &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=1266&#038;appearance=1&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;pink&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-frauen-polo-shirt.png&#8220; alt=&#8220;Human Games &#8211; Tasse &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Tasse &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=1266&#038;appearance=1&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;rosa&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-frauen-polo-shirt.png&#8220; alt=&#8220;Human Games&#8220; title_text=&#8220;Human Games&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=1266&#038;appearance=365&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;lila&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Kissenbezug&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/kissenbezuege\/\" title=\"Kissen\">Kissenbezug<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10379&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-sofakissenbezug-1.png&#8220; alt=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=1049&#038;appearance=348&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-sofakissenbezug-44-x-44-cm-4.png&#8220; alt=&#8220;AAAAAABA &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAAABA &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=1049&#038;appearance=348&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-sofakissenbezug-44-x-44-c-2.png&#8220; alt=&#8220;50\/50 &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=1049&#038;appearance=610&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-sofakissenbezug-44-x-44-cm.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Sofakissen &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=1049&#038;appearance=348&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Tassen&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/tassen\/\" title=\"Tassen\">Tassen<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10380&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-tasse-1.png&#8220; alt=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=31&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-tasse-zweifarbig.png&#8220; alt=&#8220;AAAAAABA &#8211; Tasse wei\u00df &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAAABA &#8211; Tasse wei\u00df &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=268&#038;appearance=541&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-tasse.png&#8220; alt=&#8220;50\/50 &#8211; Tasse &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Tasse &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=31&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-tasse.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Tasse wei\u00df &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Tasse wei\u00df &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=31&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Taschen&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/taschen\/\" title=\"Taschen\">Taschen<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10384&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-stoffbeutel.png&#8220; alt=&#8220;Human Games &#8211; Stoffbeutel &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Stoffbeutel &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=56&#038;appearance=134&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-stoffbeutel.png&#8220; alt=&#8220;AAAAAABA &#8211; Stoffbeutel &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAAABA &#8211; Stoffbeutel &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=56&#038;appearance=2&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/07\/teilen-stoffbeutel.png&#8220; alt=&#8220;T-Shirt, Tasche, Pullover, Kleidung f\u00fcr Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=56&#038;appearance=439&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-schultertasche-aus-recycling-material.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Stoffbeutel &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Stoffbeutel &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=56&#038;appearance=439&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Mousepad&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/mousepad\/\" title=\"Mousepad\">Mousepad<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10385&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-mousepad-querfo.png&#8220; alt=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=993&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/mobbing-t-shirt-mousepad-querformat.png&#8220; alt=&#8220;AAAAAABA &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;AAAAAABA &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/mobbing+t-shirt-A5b4cde4a222509065714625c?productType=993&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;AB&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/ausgeglichenheit-und-gleichgewicht-mousepad-querformat.png&#8220; alt=&#8220;50\/50 &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;50\/50 &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/ausgeglichenheit+und+gleichgewicht-A5b4cddde222509065713e5cd?productType=993&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;altersarmut&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-mousepad-querformat.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Auf meine Kosten &#8211; Mousepad &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/auf+meine+kosten-A5b4d9ce3e4474232d6dfbadc?productType=993&#038;appearance=1&#038;size=29&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;Auf meiner kosten&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Auf meine Kosten&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/auf-meine-kosten\/\" title=\"Auf meine Kosten\">Auf meine Kosten<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10381&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-kontrast-hoodie.png&#8220; alt=&#8220;auf-meine-kosten-kontrast-hoodie&#8220; title_text=&#8220;auf-meine-kosten-kontrast-hoodie&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/mobbing+t-shirt?&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;blau&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-schultertasche-aus-recycling-material.png&#8220; alt=&#8220;auf-meine-kosten-schultertasche-aus-recycling-material&#8220; title_text=&#8220;auf-meine-kosten-schultertasche-aus-recycling-material&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/mobbing+t-shirt?&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;grau&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-frauen-premium-langarmshirt.png&#8220; alt=&#8220;auf-meine-kosten-frauen-premium-langarmshirt&#8220; title_text=&#8220;auf-meine-kosten-frauen-premium-langarmshirt&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/mobbing+t-shirt?&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;grau&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/auf-meine-kosten-frauen-premium-t-shirt.png&#8220; alt=&#8220;Auf meine Kosten &#8211; Frauen Premium T-Shirt&#8220; title_text=&#8220;Auf meine Kosten &#8211; Frauen Premium T-Shirt&#8220; url=&#8220;https:\/\/shop.spreadshirt.de\/save-society\/mobbing+t-shirt?&#8220; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;gr\u00fcn&#8220; _builder_version=&#8220;4.7.4&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|5%||5%&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Human Games&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;2px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<h3><a href=\"https:\/\/save-society.org\/home\/human-games\/\" title=\"Human Games\">Human Games<\/a><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;|8%||8%&#8220; global_module=&#8220;10382&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-t-sh_003.png&#8220; alt=&#8220;Human Games&#8220; title_text=&#8220;Human Games&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=943&#038;appearance=712&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;blau&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-bio-t-sh.png&#8220; alt=&#8220;Human Games &#8211; Stoffbeutel, Tasche&#8220; title_text=&#8220;Human Games &#8211; Stoffbeutel, Tasche&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=461&#038;appearance=294&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;pink&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-hoodie.png&#8220; alt=&#8220;Human Games &#8211; Tasse &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; title_text=&#8220;Human Games &#8211; Tasse &#8211; Diskriminierung, Mobbing, Altersarmut, Respekt, Toleranz&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=1325&#038;appearance=763&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;rosa&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/human-games-gegen-diskriminierung-kollektion-frauen-prem_002.png&#8220; alt=&#8220;Human Games&#8220; title_text=&#8220;Human Games&#8220; url=&#8220;https:\/\/save-society.org\/home\/fashion\/#!\/human+games+gegen+diskriminierung+kollektion-A5b509a835fd3e46ac41171ea?productType=813&#038;appearance=651&#8243; url_new_window=&#8220;on&#8220; use_overlay=&#8220;on&#8220; overlay_icon_color=&#8220;rgba(255,255,255,0.8)&#8220; hover_overlay_color=&#8220;rgba(0,0,0,0.8)&#8220; hover_icon=&#8220;%%114%%&#8220; align=&#8220;center&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; admin_label=&#8220;lila&#8220; _builder_version=&#8220;3.23&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;|5%||5%&#8220; custom_css_main_element=&#8220;z-index:9999;&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;MEN\u00dc SPREADSHIRT&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_3_font_size=&#8220;20px&#8220; header_3_letter_spacing=&#8220;1px&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;1%|5%|0px|5%&#8220;]<\/p>\n<p>\n<div id=\"mega-menu-wrap-max_mega_menu_4\" class=\"mega-menu-wrap\"><div class=\"mega-menu-toggle\"><div class=\"mega-toggle-blocks-left\"><div class='mega-toggle-block mega-menu-toggle-animated-block mega-toggle-block-1' id='mega-toggle-block-1'><button aria-controls=\"mega-menu-max_mega_menu_4\" aria-expanded=\"false\" aria-haspopup=\"true\" aria-label=\"Toggle Menu\" class=\"mega-toggle-animated mega-toggle-animated-slider\" type=\"button\">\n                  <span class=\"mega-toggle-animated-box\">\n                    <span class=\"mega-toggle-animated-inner\"><\/span>\n                  <\/span>\n                <\/button><\/div><\/div><div class=\"mega-toggle-blocks-center\"><\/div><div class=\"mega-toggle-blocks-right\"><\/div><\/div><ul id=\"mega-menu-max_mega_menu_4\" class=\"mega-menu max-mega-menu mega-menu-horizontal mega-no-js\" data-event=\"click\" data-effect=\"slide\" data-effect-speed=\"200\" data-effect-mobile=\"slide\" data-effect-speed-mobile=\"200\" data-mobile-force-width=\"false\" data-second-click=\"go\" data-document-click=\"collapse\" data-vertical-behaviour=\"standard\" data-breakpoint=\"1000\" data-unbind=\"true\" data-mobile-state=\"collapse_all\" data-mobile-direction=\"vertical\"><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10449\" id=\"mega-menu-item-10449\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/all\">ALLE PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10450\" id=\"mega-menu-item-10450\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner?q=D1\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10450\">M\u00c4NNER<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10450'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10451\" id=\"mega-menu-item-10451\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner?q=D1\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10452\" id=\"mega-menu-item-10452\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+t-shirts?q=P24\">T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10453\" id=\"mega-menu-item-10453\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+langarmshirts?q=P25\">LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10454\" id=\"mega-menu-item-10454\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+pullover+%26+hoodies?q=P27\">PULLOVER & HOODIES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10455\" id=\"mega-menu-item-10455\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+jacken+%26+westen?q=P28\">JACKEN & WESTEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10456\" id=\"mega-menu-item-10456\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+poloshirts?q=P26\">POLOSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10457\" id=\"mega-menu-item-10457\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+tank+tops?q=P101\">TANK TOPS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10458\" id=\"mega-menu-item-10458\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+bioprodukte?q=P68\">BIO PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10459\" id=\"mega-menu-item-10459\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+sportbekleidung?q=P92\">SPORT BEKLEIDUNG<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10460\" id=\"mega-menu-item-10460\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/m%C3%A4nner+arbeitskleidung?q=P97ciety.org\/home\/fashion\/?cookie-state-change=1557338811035#!\/m%C3%A4nner+arbeitskleidung?q=P97\">ARBEITSKLEIDUNG<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10461\" id=\"mega-menu-item-10461\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen?q=D3\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10461\">FRAUEN<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10461'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10462\" id=\"mega-menu-item-10462\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen?q=D3\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10463\" id=\"mega-menu-item-10463\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+t-shirts?q=P33\">T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10464\" id=\"mega-menu-item-10464\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+langarmshirts?q=P35\">LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10465\" id=\"mega-menu-item-10465\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+pullover+%26+hoodies?q=P37\">PULLOVER & HOODIES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10466\" id=\"mega-menu-item-10466\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+jacken+%26+westen?q=P38\">JACKEN & WESTEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10467\" id=\"mega-menu-item-10467\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+poloshirts?q=P36\">POLOSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10468\" id=\"mega-menu-item-10468\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+tops?q=P34\">TOPS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10469\" id=\"mega-menu-item-10469\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+bioprodukte?q=P69\">BIO PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10470\" id=\"mega-menu-item-10470\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+sportbekleidung?q=P91\">SPORT BEKLEIDUNG<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10471\" id=\"mega-menu-item-10471\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/frauen+arbeitskleidung?q=P98\">ARBEITSKLEIDUNG<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10472\" id=\"mega-menu-item-10472\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys?q=D4\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10472\">KINDER & BABYS<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10472'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10473\" id=\"mega-menu-item-10473\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys?q=D4\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10474\" id=\"mega-menu-item-10474\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+t-shirts?q=P40\">T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10475\" id=\"mega-menu-item-10475\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+langarmshirts?q=P93\">LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10476\" id=\"mega-menu-item-10476\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+pullover+%26+hoodies?q=P41\">PULLOVER & HOODIES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10477\" id=\"mega-menu-item-10477\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+t-shirts?q=P42\">BABY T-SHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10478\" id=\"mega-menu-item-10478\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+langarmshirts?q=P94\">BABY LANGARMSHIRTS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10479\" id=\"mega-menu-item-10479\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+bodys?q=P43\">BABY BODYS<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10480\" id=\"mega-menu-item-10480\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+bioprodukte?q=P61\">BIO PRODUKTE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10481\" id=\"mega-menu-item-10481\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+accessoires?q=P77\">ACCESSOIRES<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10482\" id=\"mega-menu-item-10482\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/kinder+%26+babys+baby+l%C3%A4tzchen?q=P44\">BABY L\u00c4TZCHEN<\/a><\/li><\/ul>\n<\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-has-children mega-align-bottom-left mega-menu-flyout mega-menu-item-10483\" id=\"mega-menu-item-10483\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires?q=D5\" aria-expanded=\"false\" aria-controls=\"mega-sub-menu-10483\">ACCESSOIRES<span class=\"mega-indicator\" aria-hidden=\"true\"><\/span><\/a>\n<ul class=\"mega-sub-menu\" id='mega-sub-menu-10483'>\n<li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10484\" id=\"mega-menu-item-10484\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires?q=D5\">ALLE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10485\" id=\"mega-menu-item-10485\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+caps+%26+m%C3%BCtzen?q=P46\">CAPS & M\u00dcTZEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10486\" id=\"mega-menu-item-10486\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+sonstiges?q=P58\">HANDY & TABLET<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10487\" id=\"mega-menu-item-10487\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+taschen+%26+rucks%C3%A4cke?q=P47\">TASCHEN & RUCKS\u00c4CKE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10488\" id=\"mega-menu-item-10488\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+sch%C3%BCrzen?q=P48\">SCH\u00dcRZEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10489\" id=\"mega-menu-item-10489\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+kuscheltiere?q=P53\">KUSCHELTIERE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10490\" id=\"mega-menu-item-10490\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+tassen+%26+zubeh%C3%B6r?q=P49\">TASSEN & ZUBEH\u00d6R<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10491\" id=\"mega-menu-item-10491\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+kissen?q=P133\">KISSENBEZ\u00dcGE<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10492\" id=\"mega-menu-item-10492\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+buttons+%26+anstecker?q=P50\">BUTTONS & ANSTECKER<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10493\" id=\"mega-menu-item-10493\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires?q=D5\">FEIERN & SCHENKEN<\/a><\/li><li class=\"mega-menu-item mega-menu-item-type-custom mega-menu-item-object-custom mega-menu-item-10494\" id=\"mega-menu-item-10494\"><a class=\"mega-menu-link\" href=\"https:\/\/shop.spreadshirt.de\/save-society\/accessoires+sonstiges?q=P58\">SONSTIGE<\/a><\/li><\/ul>\n<\/li><\/ul><\/div><br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.19.9&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px|||&#8220; custom_padding=&#8220;|5%||5%&#8220; global_module=&#8220;9818&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Helfen Sie mit&#8220; _builder_version=&#8220;4.7.3&#8243; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; header_text_align=&#8220;justify&#8220; header_text_color=&#8220;#ffffff&#8220; text_orientation=&#8220;justified&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;|5%||5%&#8220;]<\/p>\n<p>Helfen Sie mit und spenden Sie uns einen kleinen Beitrag f\u00fcr unsere Arbeit. Nur so, k\u00f6nnen wir den t\u00e4glichen Kampf gegen die Probleme aufnehmen. Wir verwenden Ihre Spende zur Umsetzung unserer gemeinn\u00fctzigen Ziele und Projekte. Wenn Sie f\u00fcr ein spezielles Projekt: <a href=\"https:\/\/save-society.org\/home\/spenden\/\" rel=\"noopener noreferrer\" target=\"_blank\" title=\"Spenden\">Spenden <\/a>m\u00f6chten und noch weitere Fragen haben, dann kontaktieren Sie uns unter: <a href=\"mailto:spenden@save-society.org\" rel=\"noopener noreferrer\" target=\"_blank\">spenden@save-society.org<\/a>. Wir helfen Ihnen gerne bei der Auswahl f\u00fcr ein passendes Projekt weiter. Online Spenden \u00fcber PayPal: Sie werden durch einen Klick auf den gelben Button &#8222;Spenden&#8220; automatisch auf die PayPal Webseite weitergeleitet. Dort k\u00f6nnen Sie dann Ihre Spende einfach erstellen.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;Spendenbutton &#8211; PayPal&#8220; _builder_version=&#8220;3.27.4&#8243; text_text_color=&#8220;#ffffff&#8220; header_text_align=&#8220;justify&#8220; header_text_color=&#8220;#ffffff&#8220; text_orientation=&#8220;justified&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px|5%|0px|5%&#8220;]<\/p>\n<form action=\"https:\/\/www.paypal.com\/cgi-bin\/webscr\" method=\"post\" target=\"_blank\"><input name=\"cmd\" type=\"hidden\" value=\"_s-xclick\"><input name=\"hosted_button_id\" type=\"hidden\" value=\"P9APX6XJRAEG2\"><br \/><input alt=\"\" name=\"submit\" src=\"https:\/\/www.paypalobjects.com\/de_DE\/DE\/i\/btn\/btn_donateCC_LG.gif\" type=\"image\"><\/form>\n<p>[\/et_pb_text][et_pb_social_media_follow follow_button=&#8220;on&#8220; _builder_version=&#8220;4.7.3&#8243; text_orientation=&#8220;left&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;0px||0px|5%&#8220; custom_padding=&#8220;0px||0px|&#8220;][et_pb_social_media_follow_network social_network=&#8220;facebook&#8220; url=&#8220;https:\/\/www.facebook.com\/savesociety.eu\/&#8220; _builder_version=&#8220;4.7.3&#8243; background_color=&#8220;#3b5998&#8243; follow_button=&#8220;on&#8220; url_new_window=&#8220;on&#8220;]<\/p>\n<p>Facebook<\/p>\n<p>[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;3.5.1&#8243; height=&#8220;0px&#8220; custom_padding=&#8220;||100px|&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;3.19.6&#8243; height=&#8220;0px&#8220; custom_padding=&#8220;||50px|&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Service Section&#8220; _builder_version=&#8220;3.22&#8243; background_image=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/06\/save-society-org_africa_002-1.jpg&#8220; parallax=&#8220;on&#8220; parallax_method=&#8220;off&#8220; background_video_width=&#8220;1920&#8243; background_video_height=&#8220;1200&#8243; allow_player_pause=&#8220;on&#8220; custom_margin=&#8220;0px|0px|0px|0px&#8220; custom_padding=&#8220;0px|0px|0px|0px&#8220;][et_pb_row _builder_version=&#8220;3.25&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;3.5.1&#8243; height=&#8220;0px&#8220; custom_padding=&#8220;||100px|&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8220;3.19.9&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; module_alignment=&#8220;center&#8220; global_module=&#8220;9920&#8243;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_blurb title=&#8220;FOTOAUSSTELLUNG&#8220; url=&#8220;https:\/\/save-society.org\/home\/fotoausstellung\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%100%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;FOTOAUSSTELLUNG&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;4.7.3&#8243; header_level=&#8220;h5&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/fotoausstellung\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;SUCHEN&#8220; url=&#8220;https:\/\/save-society.org\/home\/save-search\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%52%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;SUCHEN&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;3.19.9&#8243; header_level=&#8220;h5&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/save-search\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_blurb title=&#8220;VORTR\u00c4GE&#8220; url=&#8220;https:\/\/save-society.org\/home\/vortrag\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%259%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;VORTR\u00c4GE&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;3.19.9&#8243; header_level=&#8220;h5&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/vortrag\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;THEMEN&#8220; url=&#8220;https:\/\/save-society.org\/home\/themen\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%86%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;THEMEN&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;3.19.9&#8243; header_level=&#8220;h5&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/themenn\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_blurb title=&#8220;MOBBING&#8220; url=&#8220;https:\/\/save-society.org\/home\/mobbing\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%257%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;MOBBING&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;3.17.6&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/mobbing\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;SPRACHE&#8220; url=&#8220;https:\/\/save-society.org\/home\/sprache\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%89%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;SPRACHE&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;3.17.6&#8243; header_level=&#8220;h5&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/sprache\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_blurb title=&#8220;DISKRIMINIERUNG&#8220; url=&#8220;https:\/\/save-society.org\/home\/diskriminierung\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%246%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;DISKRIMINIERU&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;3.19.9&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/diskriminierung\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;MACH MIT&#8220; url=&#8220;https:\/\/save-society.org\/home\/mach-mit\/&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;%%151%%&#8220; icon_color=&#8220;#ffffff&#8220; use_icon_font_size=&#8220;on&#8220; icon_font_size=&#8220;50px&#8220; admin_label=&#8220;MACH MIT&#8220; module_class=&#8220;blurb-8&#8243; _builder_version=&#8220;3.19.9&#8243; header_level=&#8220;h5&#8243; header_font=&#8220;OpenSans-SemiBold|700|||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;10px&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.4em&#8220; body_font=&#8220;OpenSans-Regular||||||||&#8220; body_text_color=&#8220;#ffffff&#8220; body_font_size=&#8220;16px&#8220; body_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;30px|30px|30px|30px&#8220; animation_style=&#8220;zoom&#8220; link_option_url=&#8220;https:\/\/save-society.org\/home\/mach-mit\/&#8220; border_color_all=&#8220;#dddddd&#8220; use_border_color=&#8220;on&#8220;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;3.5.1&#8243; height=&#8220;0px&#8220; custom_padding=&#8220;||100px|&#8220;][\/et_pb_divider][et_pb_text admin_label=&#8220;sg_popup id=6799&#8243; _builder_version=&#8220;3.27.4&#8243; custom_margin=&#8220;0px|0px|0px|0px&#8220; custom_padding=&#8220;0px|0px|0px|0px&#8220; saved_tabs=&#8220;all&#8220;]<\/p>\n<p>\n<br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Contact Form Section&#8220; _builder_version=&#8220;3.22&#8243; background_image=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/06\/save-society-org_africa_006-1.jpg&#8220; parallax=&#8220;on&#8220; parallax_method=&#8220;off&#8220; custom_padding=&#8220;110px||110px|&#8220; animation_direction=&#8220;bottom&#8220; saved_tabs=&#8220;all&#8220;][et_pb_row admin_label=&#8220;Contact Form&#8220; _builder_version=&#8220;3.25&#8243; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px||0px|&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;3.10.1&#8243; height=&#8220;0px&#8220; custom_margin=&#8220;5%|||&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;Service Section Title&#8220; _builder_version=&#8220;3.22&#8243; background_color=&#8220;rgba(0,0,0,0.75)&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||10px|&#8220; custom_padding=&#8220;|5%||5%&#8220; animation_style=&#8220;fade&#8220; animation_direction=&#8220;top&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; use_custom_width=&#8220;on&#8220; custom_width_percent=&#8220;100%&#8220; global_module=&#8220;9243&#8243; locked=&#8220;off&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Wie k\u00f6nnen wir Ihnen weiterhelfen?&#8220; _builder_version=&#8220;4.7.3&#8243; text_font=&#8220;OpenSans-Regular||||||||&#8220; text_text_color=&#8220;#ffffff&#8220; text_font_size=&#8220;16px&#8220; text_letter_spacing=&#8220;1px&#8220; text_line_height=&#8220;1.9em&#8220; header_font=&#8220;OpenSans-Regular||||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_letter_spacing=&#8220;1px&#8220; header_2_font=&#8220;OpenSans-SemiBold|||on|||||&#8220; header_2_font_size=&#8220;30px&#8220; header_2_letter_spacing=&#8220;1px&#8220; header_2_line_height=&#8220;1.3em&#8220; text_orientation=&#8220;center&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;5%|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;bottom&#8220; animation_intensity_slide=&#8220;4%&#8220; border_radii=&#8220;on|5px|5px|5px|5px&#8220;]<\/p>\n<h2>Wie k\u00f6nnen wir Ihnen weiterhelfen?<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;Sie m\u00f6chten sich regelm\u00e4\u00dfig \u00fcber&#8220; _builder_version=&#8220;4.7.3&#8243; text_font=&#8220;OpenSans-Regular||||||||&#8220; text_text_color=&#8220;#ffffff&#8220; text_font_size=&#8220;18px&#8220; text_letter_spacing=&#8220;1px&#8220; text_line_height=&#8220;1.8em&#8220; header_font=&#8220;OpenSans-Regular||||||||&#8220; header_text_color=&#8220;#ffffff&#8220; header_font_size=&#8220;20px&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;center&#8220; max_width=&#8220;800px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;|||&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;bottom&#8220; animation_delay=&#8220;100ms&#8220; animation_intensity_slide=&#8220;4%&#8220;]<\/p>\n<p>Sie m\u00f6chten sich regelm\u00e4\u00dfig \u00fcber unsere Projekte und Mitteilungen informieren? Dann abonnieren Sie jetzt unseren <a href=\"https:\/\/save-society.org\/home\/newsletter\/\">Newsletter<\/a> oder kontaktieren Sie uns:<\/p>\n<p>[\/et_pb_text][et_pb_contact_form email=&#8220;anfrage@save-society.org&#8220; custom_message=&#8220;Save Society||et_pb_line_break_holder||Kontaktformular auf der Webseite||et_pb_line_break_holder||||et_pb_line_break_holder||Art der Anfrage:||et_pb_line_break_holder||%%Selekt_Art_der_Anfrage%%||et_pb_line_break_holder||||et_pb_line_break_holder||Vor- und Nachname:||et_pb_line_break_holder||%%Ihr_Name_und_Vorname%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Allgemeine Anfrage:||et_pb_line_break_holder||%%Selekt_Allgemein%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Hilfe:||et_pb_line_break_holder||%%Selekt_Hilfe%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Sonstiges:||et_pb_line_break_holder||%%Selekt_Sonstiges%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Grund R\u00fcckruf:||et_pb_line_break_holder||%%Selekt_Rueckruf_Grund%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Grund R\u00fcckruf Telefonnummer:||et_pb_line_break_holder||%%Selekt_R\u00fcckruf_Telefonnummer%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Grund R\u00fcckruf Ab wann zur\u00fcckrufen:||et_pb_line_break_holder||%%Selekt_Rueckruf_Abwann%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Grund R\u00fcckruf Firma:||et_pb_line_break_holder||%%Selekt_R\u00fcckruf_Firma%%||et_pb_line_break_holder||||et_pb_line_break_holder||Auswahl Grund R\u00fcckruf Hinweis:||et_pb_line_break_holder||%%Hinweis_Rueckruf%%||et_pb_line_break_holder||||et_pb_line_break_holder||Hiweis Hilfe angezeigt:||et_pb_line_break_holder||%%Hinweis_Hilfe%%||et_pb_line_break_holder||||et_pb_line_break_holder||Hinweis Press angezeigt:||et_pb_line_break_holder||%%Hinweis_Presse%%||et_pb_line_break_holder||||et_pb_line_break_holder||Hinweis Bewerbung angezeigt:||et_pb_line_break_holder||%%Hinweis_Bewerbung%%||et_pb_line_break_holder||||et_pb_line_break_holder||Hinweis Datenschutz angezeigt:||et_pb_line_break_holder||%%Hinweis_Datenschutz%%||et_pb_line_break_holder||||et_pb_line_break_holder||Name des Unternehmens:||et_pb_line_break_holder||%%Name_Unternehmen%%||et_pb_line_break_holder||||et_pb_line_break_holder||Name des Verlages, Senders, Zeitung:||et_pb_line_break_holder||%%Name_Presse%%||et_pb_line_break_holder||||et_pb_line_break_holder||E-Mail Adressen||et_pb_line_break_holder||%%Ihre_Email%%||et_pb_line_break_holder||||et_pb_line_break_holder||Betreff:||et_pb_line_break_holder||%%Ihr_Betreff_Nachricht%%||et_pb_line_break_holder||||et_pb_line_break_holder||Nachricht:||et_pb_line_break_holder||%%Ihre_Nachricht%%||et_pb_line_break_holder||||et_pb_line_break_holder||Post Anschrift:||et_pb_line_break_holder||%%Ihre_Post_Adresse%%||et_pb_line_break_holder||||et_pb_line_break_holder||Telefonnummer:||et_pb_line_break_holder||%%Ihre_Telefonnummer%%||et_pb_line_break_holder||||et_pb_line_break_holder||Wann d\u00fcrfen wir anrufen?||et_pb_line_break_holder||%%Wann_duerfen_wir_Sie_Anrufen%%||et_pb_line_break_holder||||et_pb_line_break_holder||Teilname an der Umfrage:||et_pb_line_break_holder||%%Umfrage_Teilname%%||et_pb_line_break_holder||||et_pb_line_break_holder||Bewertung Umfrage:||et_pb_line_break_holder||%%Umfrage_Webseite%%||et_pb_line_break_holder||||et_pb_line_break_holder||Hinweis Danke angezeigt:||et_pb_line_break_holder||%%Hinweis_Danke_Hilfe%%||et_pb_line_break_holder||||et_pb_line_break_holder||Bewertung Umfrage Meinung:||et_pb_line_break_holder||%%Umfrage_Meinung%%||et_pb_line_break_holder||||et_pb_line_break_holder||Ich bin mit den Datenschutzbestimmungen einverstanden:||et_pb_line_break_holder||%%DSGVO_Datenschutzhinweise_gelesen_und_Einverstanden%%&#8220; use_redirect=&#8220;on&#8220; redirect_url=&#8220;https:\/\/save-society.org\/home\/befragung-meldung\/&#8220; submit_button_text=&#8220;Senden&#8220; module_id=&#8220;et_pb_contact_form_0&#8243; _builder_version=&#8220;4.7.3&#8243; form_field_background_color=&#8220;rgba(0,0,0,0.5)&#8220; form_field_text_color=&#8220;#ffffff&#8220; form_field_focus_background_color=&#8220;rgba(0,0,0,0.5)&#8220; form_field_focus_text_color=&#8220;#ffffff&#8220; title_font=&#8220;OpenSans-Regular||||||||&#8220; title_text_color=&#8220;#ffffff&#8220; title_letter_spacing=&#8220;1px&#8220; captcha_text_color=&#8220;#ffffff&#8220; captcha_letter_spacing=&#8220;1px&#8220; form_field_font=&#8220;OpenSans-Regular||||||||&#8220; form_field_text_align=&#8220;left&#8220; form_field_letter_spacing=&#8220;1px&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;16&#8243; button_text_color=&#8220;#ffffff&#8220; button_border_color=&#8220;#ffffff&#8220; button_border_radius=&#8220;100px&#8220; button_letter_spacing=&#8220;2px&#8220; button_font=&#8220;OpenSans-SemiBold|700||on|||||&#8220; button_icon=&#8220;%%109%%&#8220; button_icon_color=&#8220;#ffffff&#8220; max_width=&#8220;90%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||0px|0px&#8220; custom_padding=&#8220;||0px|0px&#8220; animation_style=&#8220;fade&#8220; custom_css_captcha_field=&#8220;color: #fff !important;&#8220; custom_css_captcha_label=&#8220;color: #fff !important;&#8220; border_radii=&#8220;on|8px|8px|8px|8px&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;#ffffff&#8220; box_shadow_style=&#8220;preset7&#8243; box_shadow_horizontal=&#8220;0px&#8220; box_shadow_vertical=&#8220;-1px&#8220; box_shadow_color=&#8220;rgba(0,0,0,0.18)&#8220; form_background_color=&#8220;rgba(0,0,0,0.5)&#8220; button_text_color_hover=&#8220;#ffffff&#8220; button_bg_color_hover=&#8220;rgba(0,0,0,0)&#8220; button_border_color_hover=&#8220;#ffffff&#8220; button_letter_spacing_hover=&#8220;2px&#8220;][et_pb_contact_field field_id=&#8220;Ihr_Name_und_Vorname&#8220; field_title=&#8220;Ihr Vor- und Nachname&#8220; min_length=&#8220;3&#8243; max_length=&#8220;50&#8243; fullwidth_field=&#8220;on&#8220; _builder_version=&#8220;4.4.3&#8243; form_field_text_color=&#8220;#ffffff&#8220; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_Art_der_Anfrage&#8220; field_title=&#8220; &#8220; field_type=&#8220;radio&#8220; radio_options=&#8220;%91{%22value%22:%22Allgemeine Anfrage%22,%22checked%22:0},{%22value%22:%22R\u00fcckruf%22,%22checked%22:0},{%22value%22:%22Hilfe%22,%22checked%22:0},{%22value%22:%22Sonstiges%22,%22checked%22:0}%93&#8243; fullwidth_field=&#8220;on&#8220; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(0,0,0,0.75)&#8220; form_field_font=&#8220;||||||||&#8220; form_field_font_size=&#8220;17&#8243; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; form_field_font_size_tablet=&#8220;18&#8243; form_field_font_size_phone=&#8220;18&#8243; field_background_color=&#8220;rgba(0,0,0,0.75)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_Allgemein&#8220; field_title=&#8220;Allgemein &#8220; field_type=&#8220;radio&#8220; radio_options=&#8220;%91{%22value%22:%22Ich ben\u00f6tige Informationen%22,%22checked%22:0},{%22value%22:%22Ich habe eine Frage%22,%22checked%22:0},{%22value%22:%22Ich m\u00f6chte Helfen%22,%22checked%22:0},{%22value%22:%22Sonstiges%22,%22checked%22:0}%93&#8243; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22Allgemeine Anfrage%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(0,0,0,0.75)&#8220; form_field_font=&#8220;||||||||&#8220; form_field_font_size=&#8220;17&#8243; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; form_field_font_size_tablet=&#8220;18&#8243; form_field_font_size_phone=&#8220;18&#8243; field_background_color=&#8220;rgba(0,0,0,0.75)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_Rueckruf_Grund&#8220; field_title=&#8220;Weshalb w\u00fcnschen Sie einen R\u00fcckruf?&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22R\u00fcckruf%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_R\u00fcckruf_Telefonnummer&#8220; field_title=&#8220;Ihre Telefonnummer&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22R\u00fcckruf%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_rueckruf_grund%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_Rueckruf_Abwann&#8220; field_title=&#8220;Ab wann d\u00fcrfen wir Sie zur\u00fcckrufen?&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22R\u00fcckruf%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_rueckruf_grund%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_R\u00fcckruf_Firma&#8220; field_title=&#8220;Name Unternehmen\/Privat&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22R\u00fcckruf%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_rueckruf_grund%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Hinweis_Rueckruf&#8220; field_title=&#8220;Hinweis: Wir k\u00f6nnen leider keine Psychologische- oder Rechtsberatung anbieten. In diesem Fall, z\u00f6gern Sie nicht &#8211; wenden Sie sich bitte an die jeweilige Stelle. Lassen Sie sich von einem professionellen Arzt oder Anwalt beraten.&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22R\u00fcckruf%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_rueckruf_grund%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(255,255,255,0)&#8220; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; border_color_all=&#8220;rgba(255,255,255,0)&#8220; field_background_color=&#8220;rgba(255,255,255,0)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_Hilfe&#8220; field_title=&#8220; Hilfe&#8220; field_type=&#8220;radio&#8220; radio_options=&#8220;%91{%22value%22:%22Hilfe bei Mobbing in der Schule%22,%22checked%22:0},{%22value%22:%22Hilfe bei Mobbing in der Arbeit%22,%22checked%22:0},{%22value%22:%22Hilfe bei Mobbing allgemein%22,%22checked%22:0},{%22value%22:%22Hilfe bei Diskriminierung%22,%22checked%22:0},{%22value%22:%22Hilfe bei Altersarmut%22,%22checked%22:0},{%22value%22:%22Hilfe bei Armut%22,%22checked%22:0},{%22value%22:%22Sonstiges%22,%22checked%22:0}%93&#8243; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22Hilfe%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(0,0,0,0.75)&#8220; form_field_font=&#8220;||||||||&#8220; form_field_font_size=&#8220;17&#8243; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; form_field_font_size_tablet=&#8220;18&#8243; form_field_font_size_phone=&#8220;18&#8243; field_background_color=&#8220;rgba(0,0,0,0.75)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Selekt_Sonstiges&#8220; field_title=&#8220; Sonstiges&#8220; field_type=&#8220;radio&#8220; radio_options=&#8220;%91{%22value%22:%22Anfragen Presse%22,%22checked%22:0},{%22value%22:%22Anfragen Unternehmen%22,%22checked%22:0},{%22value%22:%22Fragen zum Datenschutz%22,%22checked%22:0},{%22value%22:%22Fragen zum Sponsoring%22,%22checked%22:0},{%22value%22:%22Fragen zur Spende%22,%22checked%22:0},{%22value%22:%22Fragen zur Bewerbung%22,%22checked%22:0},{%22value%22:%22Sonstiges%22,%22checked%22:0}%93&#8243; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22Sonstiges%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(0,0,0,0.75)&#8220; form_field_font=&#8220;||||||||&#8220; form_field_font_size=&#8220;17&#8243; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; form_field_font_size_tablet=&#8220;18&#8243; form_field_font_size_phone=&#8220;18&#8243; field_background_color=&#8220;rgba(0,0,0,0.75)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Hinweis_Hilfe&#8220; field_title=&#8220;Hinweis: Wir k\u00f6nnen leider keine Psychologische- oder Rechtsberatung anbieten. In diesem Fall, z\u00f6gern Sie nicht &#8211; wenden Sie sich bitte an die jeweilige Stelle. Lassen Sie sich von einem professionellen Arzt oder Anwalt beraten.&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22Hilfe%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_hilfe%22,%22condition%22:%22is not empty%22,%22value%22:null}%93&#8243; _builder_version=&#8220;4.4.3&#8243; form_field_background_color=&#8220;rgba(255,255,255,0)&#8220; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; border_color_all=&#8220;rgba(255,255,255,0)&#8220; field_background_color=&#8220;rgba(255,255,255,0)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Hinweis_Presse&#8220; field_title=&#8220;Hinweis: Besuchen Sie auch unseren speziellen Presse-Bereich unter %22Presse%22 oder informieren Sie sich \u00fcber unsere Pressemitteilungen und aktuellen Nachrichten im Bereich %22Aktuelles%22.&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22Sonstiges%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_sonstiges%22,%22condition%22:%22is%22,%22value%22:%22Anfragen Presse%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(255,255,255,0)&#8220; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; border_color_all=&#8220;rgba(255,255,255,0)&#8220; field_background_color=&#8220;rgba(255,255,255,0)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Hinweis_Bewerbung&#8220; field_title=&#8220;Hinweis: Falls Sie sich bei uns bewerben m\u00f6chten, verwenden Sie bitte das Formular der jeweiligen Stellenbeschreibung.&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22Sonstiges%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_sonstiges%22,%22condition%22:%22is%22,%22value%22:%22Fragen zur Bewerbung%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(255,255,255,0)&#8220; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; border_color_all=&#8220;rgba(255,255,255,0)&#8220; field_background_color=&#8220;rgba(255,255,255,0)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Hinweis_Datenschutz&#8220; field_title=&#8220;Hinweis: Beschreiben Sie bitte genau Ihr Anliegen. Falls notwendig, belegen Sie bitte die Quellen durch die Web-Adresse oder den genauen Text. M\u00f6chten Sie wissen, was mit Ihren Daten passiert oder m\u00f6chten Sie etwas l\u00f6schen lassen? Z\u00f6gern Sie nicht, wir sind gerne behilflich.&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is%22,%22value%22:%22Sonstiges%22},{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_sonstiges%22,%22condition%22:%22is%22,%22value%22:%22Fragen zum Datenschutz%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(255,255,255,0)&#8220; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; border_color_all=&#8220;rgba(255,255,255,0)&#8220; field_background_color=&#8220;rgba(255,255,255,0)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Name_Unternehmen&#8220; field_title=&#8220;Der Name des Unternehmens&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22selekt_sonstiges%22,%22condition%22:%22is%22,%22value%22:%22Anfragen Unternehmen%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Name_Presse&#8220; field_title=&#8220;Nenne Sie uns bitte den Namen des Sender, der Zeitung, Verlages oder Medium.&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22selekt_sonstiges%22,%22condition%22:%22is%22,%22value%22:%22Anfragen Presse%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Ihre_Email&#8220; field_title=&#8220;Ihre E-Mail Adresse&#8220; field_type=&#8220;email&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not%22,%22value%22:%22R\u00fcckruf%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Ihr_Betreff_Nachricht&#8220; field_title=&#8220;Betreff Ihrer Nachricht&#8220; min_length=&#8220;4&#8243; max_length=&#8220;39&#8243; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22ihre_email%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;4.7.3&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Ihre_Nachricht&#8220; field_title=&#8220;Ihre Nachricht&#8220; field_type=&#8220;text&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Ihre_Post_Adresse&#8220; field_title=&#8220;Bei Bedarf Ihre Post Anschrift&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22ihre_email%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22ihre_nachricht%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Ihre_Telefonnummer&#8220; field_title=&#8220;Bei Bedarf Ihre Telefonnummer&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22ihre_email%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22ihre_nachricht%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Wann_duerfen_wir_Sie_Anrufen&#8220; field_title=&#8220;Wann d\u00fcrfen wir Sie anrufen?&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22ihre_email%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22ihre_nachricht%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22ihre_telefonnummer%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Umfrage_Teilname&#8220; field_title=&#8220;M\u00f6chten Sie an einer Umfrage teilnehmen?&#8220; field_type=&#8220;radio&#8220; radio_options=&#8220;%91{%22value%22:%22Ja%22,%22checked%22:0},{%22value%22:%22Nein%22,%22checked%22:0}%93&#8243; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22ihre_email%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; form_field_font_size=&#8220;17&#8243; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220; form_field_font_size_tablet=&#8220;17&#8243; form_field_font_size_phone=&#8220;17&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Umfrage_Webseite&#8220; field_title=&#8220;Wie finden Sie diese Webseite?&#8220; field_type=&#8220;checkbox&#8220; checkbox_options=&#8220;%91{%22value%22:%22Sehr gut%22,%22checked%22:0},{%22value%22:%22Gut%22,%22checked%22:0},{%22value%22:%22Befriedigend%22,%22checked%22:0},{%22value%22:%22Ausreichend%22,%22checked%22:0},{%22value%22:%22Mangelhaft%22,%22checked%22:0},{%22value%22:%22Ungen\u00fcgend%22,%22checked%22:0}%93&#8243; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22ihre_email%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22umfrage_teilname%22,%22condition%22:%22is%22,%22value%22:%22Ja%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; form_field_font_size=&#8220;17&#8243; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220; form_field_font_size_tablet=&#8220;17&#8243; form_field_font_size_phone=&#8220;17&#8243;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Hinweis_Danke_Hilfe&#8220; field_title=&#8220;Danke f\u00fcr Ihre Hilfe!&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22umfrage_webseite%22,%22condition%22:%22is not empty%22,%22value%22:%22Sehr gut%22}%93&#8243; _builder_version=&#8220;3.23&#8243; form_field_background_color=&#8220;rgba(255,255,255,0)&#8220; form_field_font=&#8220;||||||||&#8220; form_field_font_size=&#8220;17&#8243; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; form_field_font_size_tablet=&#8220;17&#8243; form_field_font_size_phone=&#8220;17&#8243; border_color_all=&#8220;rgba(255,255,255,0)&#8220; field_background_color=&#8220;rgba(255,255,255,0)&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;Umfrage_Meinung&#8220; field_title=&#8220;Weshalb sind Sie dieser Meinung?&#8220; field_type=&#8220;text&#8220; required_mark=&#8220;off&#8220; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22ihre_email%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22selekt_art_der_anfrage%22,%22condition%22:%22is not empty%22,%22value%22:%22Allgemeine Anfrage%22},{%22field%22:%22umfrage_teilname%22,%22condition%22:%22is%22,%22value%22:%22Ja%22}%93&#8243; _builder_version=&#8220;3.19.9&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; custom_margin=&#8220;||60px|&#8220; custom_margin_tablet=&#8220;||60px|&#8220; custom_margin_phone=&#8220;||60px|&#8220; custom_padding=&#8220;|||&#8220; custom_padding_tablet=&#8220;|||&#8220; custom_padding_phone=&#8220;|||&#8220;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8220;DSGVO_Datenschutzhinweise_gelesen_und_Einverstanden&#8220; field_title=&#8220; &#8220; field_type=&#8220;checkbox&#8220; checkbox_options=&#8220;%91{%22value%22:%22* Einverstanden%22,%22checked%22:0,%22dragID%22:-1}%93&#8243; fullwidth_field=&#8220;on&#8220; conditional_logic=&#8220;on&#8220; conditional_logic_relation=&#8220;on&#8220; conditional_logic_rules=&#8220;%91{%22field%22:%22ihr_name_und_vorname%22,%22condition%22:%22is not empty%22,%22value%22:%22%22}%93&#8243; _builder_version=&#8220;4.7.3&#8243; form_field_font=&#8220;||||||||&#8220; max_width=&#8220;100%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; form_field_font_size_tablet=&#8220;20px&#8220; form_field_font_size_phone=&#8220;20px&#8220;][\/et_pb_contact_field][\/et_pb_contact_form][et_pb_divider show_divider=&#8220;off&#8220; admin_label=&#8220;Teiler 30px&#8220; _builder_version=&#8220;3.2.2&#8243; height=&#8220;0px&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|desktop&#8220; custom_padding=&#8220;30px||0px|&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;&#8220; custom_padding_last_edited=&#8220;on|desktop&#8220;][\/et_pb_divider][et_pb_text admin_label=&#8220;* Ich habe die&#8220; _builder_version=&#8220;4.7.3&#8243; text_font=&#8220;OpenSans-Regular||||||||&#8220; text_text_color=&#8220;#ffffff&#8220; text_letter_spacing=&#8220;1px&#8220; text_line_height=&#8220;1.4em&#8220; header_font=&#8220;OpenSans-Regular||||||||&#8220; header_text_align=&#8220;justify&#8220; header_2_font=&#8220;OpenSans-Regular||||||||&#8220; header_3_font=&#8220;OpenSans-Regular||||||||&#8220; text_orientation=&#8220;justified&#8220; custom_margin=&#8220;0px|||&#8220; custom_padding=&#8220;0px|5%|5%|5%&#8220;]<\/p>\n<p>* Ich habe die <a href=\"http:\/\/www.save-society.org\/home\/datenschutz\/\">Datenschutzerkl\u00e4rung<\/a> zur Kenntnis genommen. Ich stimme zu, dass meine Angaben zur Beantwortung meiner Anfrage und f\u00fcr Anschlussfragen elektronisch erhoben und gespeichert werden. Diese Daten werden nicht ohne meine Einwilligung weitergegeben. Ich kann meine Einwilligung jederzeit widerrufen. Bewertungen und Umfragen sind keine Pflichtangaben und werden zur Optimierung der Webseite verwendet.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;Contact Form&#8220; _builder_version=&#8220;3.25&#8243; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;||0px|&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;3.2&#8243; height=&#8220;0px&#8220; custom_padding=&#8220;||100px|&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geschenke Wer Menschen helfen m\u00f6chte, findet zahlreiche M\u00f6glichkeiten auf unserer Webseite. Wer eine besondere Geschenkidee sucht, findet hier verschiedene kreative Ideen. Wir haben Motive gestaltet, die einen aufkl\u00e4renden Charakter besitzen. Diese werden auf verschiedene Produkte gedruckt. Ein Hoodie, Mousepads oder ein Stoffbeutel kann die Welt nicht sonderlich besser machen. M\u00f6chte man jedoch ein Zeichen setzen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10693,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-10687","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geschenke - Save Society<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/save-society.org\/home\/geschenke\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geschenke - Save Society\" \/>\n<meta property=\"og:description\" content=\"Geschenke Wer Menschen helfen m\u00f6chte, findet zahlreiche M\u00f6glichkeiten auf unserer Webseite. Wer eine besondere Geschenkidee sucht, findet hier verschiedene kreative Ideen. Wir haben Motive gestaltet, die einen aufkl\u00e4renden Charakter besitzen. Diese werden auf verschiedene Produkte gedruckt. Ein Hoodie, Mousepads oder ein Stoffbeutel kann die Welt nicht sonderlich besser machen. M\u00f6chte man jedoch ein Zeichen setzen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/save-society.org\/home\/geschenke\/\" \/>\n<meta property=\"og:site_name\" content=\"Save Society\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/savesociety.eu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-26T09:49:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"583\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"70\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/\",\"name\":\"Geschenke - Save Society\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg\",\"datePublished\":\"2018-01-11T12:11:32+00:00\",\"dateModified\":\"2020-11-26T09:49:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg\",\"contentUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg\",\"width\":1000,\"height\":583,\"caption\":\"Geschenke Geschenkideen Shop Einkaufen Online Store - Save Society\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/geschenke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/save-society.org\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geschenke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/\",\"name\":\"Save Society\",\"description\":\"Gemeinn\u00fctzige Organisation\",\"publisher\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/save-society.org\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\",\"name\":\"Save Society\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/savesociety_logo_full.jpg\",\"contentUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/savesociety_logo_full.jpg\",\"width\":1831,\"height\":1112,\"caption\":\"Save Society\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/savesociety.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geschenke - Save Society","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/save-society.org\/home\/geschenke\/","og_locale":"de_DE","og_type":"article","og_title":"Geschenke - Save Society","og_description":"Geschenke Wer Menschen helfen m\u00f6chte, findet zahlreiche M\u00f6glichkeiten auf unserer Webseite. Wer eine besondere Geschenkidee sucht, findet hier verschiedene kreative Ideen. Wir haben Motive gestaltet, die einen aufkl\u00e4renden Charakter besitzen. Diese werden auf verschiedene Produkte gedruckt. Ein Hoodie, Mousepads oder ein Stoffbeutel kann die Welt nicht sonderlich besser machen. M\u00f6chte man jedoch ein Zeichen setzen [&hellip;]","og_url":"https:\/\/save-society.org\/home\/geschenke\/","og_site_name":"Save Society","article_publisher":"https:\/\/www.facebook.com\/savesociety.eu\/","article_modified_time":"2020-11-26T09:49:09+00:00","og_image":[{"width":1000,"height":583,"url":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"70\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/save-society.org\/home\/geschenke\/","url":"https:\/\/save-society.org\/home\/geschenke\/","name":"Geschenke - Save Society","isPartOf":{"@id":"https:\/\/save-society.org\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/save-society.org\/home\/geschenke\/#primaryimage"},"image":{"@id":"https:\/\/save-society.org\/home\/geschenke\/#primaryimage"},"thumbnailUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg","datePublished":"2018-01-11T12:11:32+00:00","dateModified":"2020-11-26T09:49:09+00:00","breadcrumb":{"@id":"https:\/\/save-society.org\/home\/geschenke\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/save-society.org\/home\/geschenke\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/save-society.org\/home\/geschenke\/#primaryimage","url":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg","contentUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/05\/geschenke-geschenkideen-shop-einkaufen-online-store-save-society.jpg","width":1000,"height":583,"caption":"Geschenke Geschenkideen Shop Einkaufen Online Store - Save Society"},{"@type":"BreadcrumbList","@id":"https:\/\/save-society.org\/home\/geschenke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/save-society.org\/home\/"},{"@type":"ListItem","position":2,"name":"Geschenke"}]},{"@type":"WebSite","@id":"https:\/\/save-society.org\/home\/#website","url":"https:\/\/save-society.org\/home\/","name":"Save Society","description":"Gemeinn\u00fctzige Organisation","publisher":{"@id":"https:\/\/save-society.org\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/save-society.org\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/save-society.org\/home\/#organization","name":"Save Society","url":"https:\/\/save-society.org\/home\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/save-society.org\/home\/#\/schema\/logo\/image\/","url":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/04\/savesociety_logo_full.jpg","contentUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/04\/savesociety_logo_full.jpg","width":1831,"height":1112,"caption":"Save Society"},"image":{"@id":"https:\/\/save-society.org\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/savesociety.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/pages\/10687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/comments?post=10687"}],"version-history":[{"count":4,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/pages\/10687\/revisions"}],"predecessor-version":[{"id":12760,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/pages\/10687\/revisions\/12760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/media\/10693"}],"wp:attachment":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/media?parent=10687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}