{"id":1486,"date":"2015-09-02T21:09:44","date_gmt":"2015-09-02T19:09:44","guid":{"rendered":"http:\/\/savesociety.org\/save\/?p=1486"},"modified":"2019-01-21T22:30:54","modified_gmt":"2019-01-21T21:30:54","slug":"ein-zeichen-fuer-menschenrechte","status":"publish","type":"post","link":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/","title":{"rendered":"Ein Zeichen f\u00fcr Menschenrechte"},"content":{"rendered":"<p>[et_pb_section bb_built=&#8220;1&#8243; _builder_version=&#8220;3.3.1&#8243; background_color=&#8220;rgba(255,255,255,0)&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px||0px|&#8220;][et_pb_row][et_pb_column type=&#8220;4_4&#8243;][et_pb_image _builder_version=&#8220;3.19.6&#8243; src=&#8220;https:\/\/save-society.org\/home\/wp-content\/uploads\/2015\/09\/monika.jpg&#8220; align=&#8220;center&#8220; alt=&#8220;Ein Zeichen f\u00fcr Menschenrechte&#8220; title_text=&#8220;Ein Zeichen f\u00fcr Menschenrechte&#8220; \/][et_pb_text _builder_version=&#8220;3.19.6&#8243; text_orientation=&#8220;justified&#8220;]<\/p>\n<h2>Ein Zeichen f\u00fcr Menschenrechte<\/h2>\n<p>Unsere SAVE SOCIETY Botschafterin Monika Sozanska setzt ein Zeichen f\u00fcr Menschenrechte.<br \/>\nFoto: Fechterinnen Ricarda Multerer und Monika Sozanska<\/p>\n<p>Die Allgemeine Erkl\u00e4rung der Menschenrechte<br \/>\nArtikel 3 &#8211; Jeder hat das Recht auf Leben, Freiheit und Sicherheit der Person.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Zeichen f\u00fcr Menschenrechte<\/p>\n","protected":false},"author":1,"featured_media":1487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>Unsere SAVE SOCIETY Botschafterin Monika Sozanska setzt ein Zeichen f\u00fcr Menschenrechte.<br \/>Foto: Fechterinnen Ricarda Multerer und Monika Sozanska<\/p><p>Die Allgemeine Erkl\u00e4rung der Menschenrechte<br \/>Artikel 3 - Jeder hat das Recht auf Leben, Freiheit und Sicherheit der Person.<\/p><p>Alle weiteren Artikel der Erkl\u00e4rung der Menschenrechte <a href=\"https:\/\/save-society.org\/home\/?p=1490\u200e\">hier<\/a>!<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-1486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Zeichen f\u00fcr Menschenrechte - Save Society<\/title>\n<meta name=\"description\" content=\"Ein Zeichen f\u00fcr Menschenrechte\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Zeichen f\u00fcr Menschenrechte - Save Society\" \/>\n<meta property=\"og:description\" content=\"Ein Zeichen f\u00fcr Menschenrechte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/\" \/>\n<meta property=\"og:site_name\" content=\"Save Society\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/savesociety.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-02T19:09:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-21T21:30:54+00:00\" \/>\n<meta name=\"author\" content=\"save-society\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"save-society\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/\"},\"author\":{\"name\":\"save-society\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/person\\\/dceaf92f93e0bcd9d9601a5eb96402f9\"},\"headline\":\"Ein Zeichen f\u00fcr Menschenrechte\",\"datePublished\":\"2015-09-02T19:09:44+00:00\",\"dateModified\":\"2019-01-21T21:30:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/\"},\"wordCount\":122,\"publisher\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/\",\"name\":\"Ein Zeichen f\u00fcr Menschenrechte - Save Society\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-09-02T19:09:44+00:00\",\"dateModified\":\"2019-01-21T21:30:54+00:00\",\"description\":\"Ein Zeichen f\u00fcr Menschenrechte\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/ein-zeichen-fuer-menschenrechte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/save-society.org\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Zeichen f\u00fcr Menschenrechte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/\",\"name\":\"Save Society\",\"description\":\"Gemeinn\u00fctzige Organisation\",\"publisher\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/save-society.org\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\",\"name\":\"Save Society\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/savesociety_logo_full.jpg\",\"contentUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/savesociety_logo_full.jpg\",\"width\":1831,\"height\":1112,\"caption\":\"Save Society\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/savesociety.eu\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/person\\\/dceaf92f93e0bcd9d9601a5eb96402f9\",\"name\":\"save-society\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Zeichen f\u00fcr Menschenrechte - Save Society","description":"Ein Zeichen f\u00fcr Menschenrechte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Zeichen f\u00fcr Menschenrechte - Save Society","og_description":"Ein Zeichen f\u00fcr Menschenrechte","og_url":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/","og_site_name":"Save Society","article_publisher":"https:\/\/www.facebook.com\/savesociety.eu\/","article_published_time":"2015-09-02T19:09:44+00:00","article_modified_time":"2019-01-21T21:30:54+00:00","author":"save-society","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"save-society","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/#article","isPartOf":{"@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/"},"author":{"name":"save-society","@id":"https:\/\/save-society.org\/home\/#\/schema\/person\/dceaf92f93e0bcd9d9601a5eb96402f9"},"headline":"Ein Zeichen f\u00fcr Menschenrechte","datePublished":"2015-09-02T19:09:44+00:00","dateModified":"2019-01-21T21:30:54+00:00","mainEntityOfPage":{"@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/"},"wordCount":122,"publisher":{"@id":"https:\/\/save-society.org\/home\/#organization"},"image":{"@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/#primaryimage"},"thumbnailUrl":"","articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/","url":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/","name":"Ein Zeichen f\u00fcr Menschenrechte - Save Society","isPartOf":{"@id":"https:\/\/save-society.org\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/#primaryimage"},"image":{"@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-09-02T19:09:44+00:00","dateModified":"2019-01-21T21:30:54+00:00","description":"Ein Zeichen f\u00fcr Menschenrechte","breadcrumb":{"@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/save-society.org\/home\/ein-zeichen-fuer-menschenrechte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/save-society.org\/home\/"},{"@type":"ListItem","position":2,"name":"Ein Zeichen f\u00fcr Menschenrechte"}]},{"@type":"WebSite","@id":"https:\/\/save-society.org\/home\/#website","url":"https:\/\/save-society.org\/home\/","name":"Save Society","description":"Gemeinn\u00fctzige Organisation","publisher":{"@id":"https:\/\/save-society.org\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/save-society.org\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/save-society.org\/home\/#organization","name":"Save Society","url":"https:\/\/save-society.org\/home\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/save-society.org\/home\/#\/schema\/logo\/image\/","url":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/04\/savesociety_logo_full.jpg","contentUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/04\/savesociety_logo_full.jpg","width":1831,"height":1112,"caption":"Save Society"},"image":{"@id":"https:\/\/save-society.org\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/savesociety.eu\/"]},{"@type":"Person","@id":"https:\/\/save-society.org\/home\/#\/schema\/person\/dceaf92f93e0bcd9d9601a5eb96402f9","name":"save-society"}]}},"_links":{"self":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":5,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts\/1486\/revisions"}],"predecessor-version":[{"id":8745,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts\/1486\/revisions\/8745"}],"wp:attachment":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/media?parent=1486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/categories?post=1486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/tags?post=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}