{"id":5789,"date":"2018-07-20T10:58:36","date_gmt":"2018-07-20T08:58:36","guid":{"rendered":"https:\/\/save-society.org\/home\/?p=5789"},"modified":"2020-11-23T11:52:42","modified_gmt":"2020-11-23T10:52:42","slug":"test-auf-psychopathie","status":"publish","type":"post","link":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/","title":{"rendered":"Psychopathie Test"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;3.22&#8243; background_color=&#8220;rgba(255,255,255,0)&#8220; custom_margin=&#8220;0px||0px|&#8220; custom_padding=&#8220;0px||0px|&#8220;][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Test auf Psychopathie&#8220; _builder_version=&#8220;4.7.3&#8243; header_text_align=&#8220;justify&#8220; text_orientation=&#8220;justified&#8220; background_layout=&#8220;dark&#8220; hover_enabled=&#8220;0&#8243; text_letter_spacing=&#8220;1px&#8220; header_letter_spacing=&#8220;1px&#8220; header_2_letter_spacing=&#8220;1px&#8220; header_3_letter_spacing=&#8220;1px&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2>PSYCHOPATH DES MONATS<\/h2>\n<p>Pressemitteilung \u00fcber die M\u00f6glichkeit einen Selbsttest auf allgemein bekannte Anzeichen auf Psychopathie zu absolvieren. Dabei k\u00f6nnen Interessierte, Fragen f\u00fcr sich oder fremde Personen beantworten und sich dadurch mit den typischen Symptomen der Psychopathie auseinandersetzen.<\/p>\n<p><strong>Psychopath des Monats<\/strong><br \/>\n<em>Pressemitteilung von: Save Society <\/em><br \/>\n<a href=\"https:\/\/www.openpr.de\/news\/1011792\/Psychopath-des-Monats.html\" target=\"_blank\" rel=\"noopener noreferrer\">Zur Pressemitteilung<\/a><br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_button button_url=&#8220;https:\/\/save-society.org\/home\/kennst-du-einen-psychopathen\/&#8220; button_text=&#8220;Zum Test&#8220; admin_label=&#8220;Taste Informationen&#8220; _builder_version=&#8220;3.19.6&#8243; custom_button=&#8220;on&#8220; button_text_size=&#8220;14&#8243; button_text_color=&#8220;#ffffff&#8220; button_border_color=&#8220;#ffffff&#8220; button_border_radius=&#8220;100px&#8220; button_letter_spacing=&#8220;2px&#8220; button_font=&#8220;OpenSans-SemiBold|700||on|||||&#8220; button_icon=&#8220;%%36%%&#8220; animation_style=&#8220;fade&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; button_text_size__hover_enabled=&#8220;off&#8220; button_text_size__hover=&#8220;null&#8220; button_one_text_size__hover_enabled=&#8220;off&#8220; button_one_text_size__hover=&#8220;null&#8220; button_two_text_size__hover_enabled=&#8220;off&#8220; button_two_text_size__hover=&#8220;null&#8220; button_text_color__hover_enabled=&#8220;on&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_one_text_color__hover_enabled=&#8220;off&#8220; button_one_text_color__hover=&#8220;null&#8220; button_two_text_color__hover_enabled=&#8220;off&#8220; button_two_text_color__hover=&#8220;null&#8220; button_border_width__hover_enabled=&#8220;off&#8220; button_border_width__hover=&#8220;null&#8220; button_one_border_width__hover_enabled=&#8220;off&#8220; button_one_border_width__hover=&#8220;null&#8220; button_two_border_width__hover_enabled=&#8220;off&#8220; button_two_border_width__hover=&#8220;null&#8220; button_border_color__hover_enabled=&#8220;on&#8220; button_border_color__hover=&#8220;#ffffff&#8220; button_one_border_color__hover_enabled=&#8220;off&#8220; button_one_border_color__hover=&#8220;null&#8220; button_two_border_color__hover_enabled=&#8220;off&#8220; button_two_border_color__hover=&#8220;null&#8220; button_border_radius__hover_enabled=&#8220;off&#8220; button_border_radius__hover=&#8220;null&#8220; button_one_border_radius__hover_enabled=&#8220;off&#8220; button_one_border_radius__hover=&#8220;null&#8220; button_two_border_radius__hover_enabled=&#8220;off&#8220; button_two_border_radius__hover=&#8220;null&#8220; button_letter_spacing__hover_enabled=&#8220;on&#8220; button_letter_spacing__hover=&#8220;2px&#8220; button_one_letter_spacing__hover_enabled=&#8220;off&#8220; button_one_letter_spacing__hover=&#8220;null&#8220; button_two_letter_spacing__hover_enabled=&#8220;off&#8220; button_two_letter_spacing__hover=&#8220;null&#8220; button_bg_color__hover_enabled=&#8220;on&#8220; button_bg_color__hover=&#8220;rgba(0,0,0,0)&#8220; button_one_bg_color__hover_enabled=&#8220;off&#8220; button_one_bg_color__hover=&#8220;null&#8220; button_two_bg_color__hover_enabled=&#8220;off&#8220; button_two_bg_color__hover=&#8220;null&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Psychopathie Test &#8211; Selbsttest auf Psychopathie | Bist du ein Psychopath? Psychopathy Checklist<\/p>\n","protected":false},"author":1,"featured_media":7379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-5789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Psychopathie Test | Schnell und einfach Selbsttest<\/title>\n<meta name=\"description\" content=\"Psychopathie Test - Selbsttest auf Psychopathie | Bist du ein Psychopath? Psychopathy Checklist\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/save-society.org\/home\/test-auf-psychopathie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Psychopathie Test | Schnell und einfach Selbsttest\" \/>\n<meta property=\"og:description\" content=\"Psychopathie Test - Selbsttest auf Psychopathie | Bist du ein Psychopath? Psychopathy Checklist\" \/>\n<meta property=\"og:url\" content=\"https:\/\/save-society.org\/home\/test-auf-psychopathie\/\" \/>\n<meta property=\"og:site_name\" content=\"Save Society\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/savesociety.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-20T08:58:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-23T10:52:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/01\/psychopathie-save-society.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"save-society\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"save-society\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/\"},\"author\":{\"name\":\"save-society\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/person\\\/dceaf92f93e0bcd9d9601a5eb96402f9\"},\"headline\":\"Psychopathie Test\",\"datePublished\":\"2018-07-20T08:58:36+00:00\",\"dateModified\":\"2020-11-23T10:52:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/\"},\"wordCount\":497,\"publisher\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/psychopathie-save-society.jpg\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/\",\"name\":\"Psychopathie Test | Schnell und einfach Selbsttest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/psychopathie-save-society.jpg\",\"datePublished\":\"2018-07-20T08:58:36+00:00\",\"dateModified\":\"2020-11-23T10:52:42+00:00\",\"description\":\"Psychopathie Test - Selbsttest auf Psychopathie | Bist du ein Psychopath? Psychopathy Checklist\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/psychopathie-save-society.jpg\",\"contentUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/psychopathie-save-society.jpg\",\"width\":1200,\"height\":699,\"caption\":\"Psychopathen Test Deutschland, Was ist ein Psychopath? Psychopathie, Soziopath, Definition, Beispiele, Arten, Pers\u00f6nlichkeitsst\u00f6rung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/test-auf-psychopathie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/save-society.org\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Psychopathie Test\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/\",\"name\":\"Save Society\",\"description\":\"Gemeinn\u00fctzige Organisation\",\"publisher\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/save-society.org\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#organization\",\"name\":\"Save Society\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/savesociety_logo_full.jpg\",\"contentUrl\":\"https:\\\/\\\/save-society.org\\\/home\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/savesociety_logo_full.jpg\",\"width\":1831,\"height\":1112,\"caption\":\"Save Society\"},\"image\":{\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/savesociety.eu\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/save-society.org\\\/home\\\/#\\\/schema\\\/person\\\/dceaf92f93e0bcd9d9601a5eb96402f9\",\"name\":\"save-society\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Psychopathie Test | Schnell und einfach Selbsttest","description":"Psychopathie Test - Selbsttest auf Psychopathie | Bist du ein Psychopath? Psychopathy Checklist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/","og_locale":"de_DE","og_type":"article","og_title":"Psychopathie Test | Schnell und einfach Selbsttest","og_description":"Psychopathie Test - Selbsttest auf Psychopathie | Bist du ein Psychopath? Psychopathy Checklist","og_url":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/","og_site_name":"Save Society","article_publisher":"https:\/\/www.facebook.com\/savesociety.eu\/","article_published_time":"2018-07-20T08:58:36+00:00","article_modified_time":"2020-11-23T10:52:42+00:00","og_image":[{"width":1200,"height":699,"url":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/01\/psychopathie-save-society.jpg","type":"image\/jpeg"}],"author":"save-society","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"save-society","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/#article","isPartOf":{"@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/"},"author":{"name":"save-society","@id":"https:\/\/save-society.org\/home\/#\/schema\/person\/dceaf92f93e0bcd9d9601a5eb96402f9"},"headline":"Psychopathie Test","datePublished":"2018-07-20T08:58:36+00:00","dateModified":"2020-11-23T10:52:42+00:00","mainEntityOfPage":{"@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/"},"wordCount":497,"publisher":{"@id":"https:\/\/save-society.org\/home\/#organization"},"image":{"@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/#primaryimage"},"thumbnailUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/01\/psychopathie-save-society.jpg","articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/","url":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/","name":"Psychopathie Test | Schnell und einfach Selbsttest","isPartOf":{"@id":"https:\/\/save-society.org\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/#primaryimage"},"image":{"@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/#primaryimage"},"thumbnailUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/01\/psychopathie-save-society.jpg","datePublished":"2018-07-20T08:58:36+00:00","dateModified":"2020-11-23T10:52:42+00:00","description":"Psychopathie Test - Selbsttest auf Psychopathie | Bist du ein Psychopath? Psychopathy Checklist","breadcrumb":{"@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/save-society.org\/home\/test-auf-psychopathie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/#primaryimage","url":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/01\/psychopathie-save-society.jpg","contentUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2019\/01\/psychopathie-save-society.jpg","width":1200,"height":699,"caption":"Psychopathen Test Deutschland, Was ist ein Psychopath? Psychopathie, Soziopath, Definition, Beispiele, Arten, Pers\u00f6nlichkeitsst\u00f6rung"},{"@type":"BreadcrumbList","@id":"https:\/\/save-society.org\/home\/test-auf-psychopathie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/save-society.org\/home\/"},{"@type":"ListItem","position":2,"name":"Psychopathie Test"}]},{"@type":"WebSite","@id":"https:\/\/save-society.org\/home\/#website","url":"https:\/\/save-society.org\/home\/","name":"Save Society","description":"Gemeinn\u00fctzige Organisation","publisher":{"@id":"https:\/\/save-society.org\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/save-society.org\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/save-society.org\/home\/#organization","name":"Save Society","url":"https:\/\/save-society.org\/home\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/save-society.org\/home\/#\/schema\/logo\/image\/","url":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/04\/savesociety_logo_full.jpg","contentUrl":"https:\/\/save-society.org\/home\/wp-content\/uploads\/2018\/04\/savesociety_logo_full.jpg","width":1831,"height":1112,"caption":"Save Society"},"image":{"@id":"https:\/\/save-society.org\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/savesociety.eu\/"]},{"@type":"Person","@id":"https:\/\/save-society.org\/home\/#\/schema\/person\/dceaf92f93e0bcd9d9601a5eb96402f9","name":"save-society"}]}},"_links":{"self":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts\/5789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/comments?post=5789"}],"version-history":[{"count":5,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts\/5789\/revisions"}],"predecessor-version":[{"id":11858,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/posts\/5789\/revisions\/11858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/media\/7379"}],"wp:attachment":[{"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/media?parent=5789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/categories?post=5789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/save-society.org\/home\/wp-json\/wp\/v2\/tags?post=5789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}